{"id":12599,"date":"2022-05-12T15:55:29","date_gmt":"2022-05-12T13:55:29","guid":{"rendered":"https:\/\/sunranxx.com\/participant\/guapaletas\/"},"modified":"2022-05-12T16:36:11","modified_gmt":"2022-05-12T14:36:11","slug":"guapaletas","status":"publish","type":"dt_portfolios","link":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/","title":{"rendered":"Guapaletas"},"content":{"rendered":"<p>Somos una empresa dedicada a la fabricaci\u00f3n y comercializaci\u00f3n de helado artesanal en una forma distinta. Helado artesanal en palito. Llegamos a Espa\u00f1a hace m\u00e1s de un a\u00f1o y estamos presentes en varios puntos de Europa.<\/p>\n<p>Presentamos una forma distinta de tomar helado, con productos de fabricaci\u00f3n propia y comercializando m\u00e1s de 23 sabores 100% naturales, sin colorantes ni conservantes.<\/p>\n<p>Seleccionamos los ingredientes m\u00e1s nobles y naturales para garantizar la mejor calidad de elaboraci\u00f3n de nuestros helados.<\/p>\n<p>Somos especialistas en destacar la excelencia del sabor artesanal para todas las personas.<\/p>\n<p>Utilizamos solamente fruta fresca, zumos reci\u00e9n exprimidos y la mejor materia prima para que nuestros helados sean \u00fanicos. No a\u00f1adimos conservantes ni colorantes artificiales a nuestros productos, de esta forma cuidamos las propiedades originales de los mismos.<\/p>\n<p>Encontraras alegr\u00eda en una innovadora forma de disfrutar la frescura de un helado del verano, lo goloso de un bocado cremoso y la sorpresa de un relleno que no esperabas.<\/p>\n<p>Hemos venido para hacer explotar tus sentidos.<\/p>\n<p>\u00a0<\/p>\n<p>Productos adicionales:<br \/>\n\u2013 Zumos Naturales Innocent<br \/>\n\u2013 Caf\u00e9 Nespresso<br \/>\n\u2013 Agua Cabreiroa 33ml<br \/>\n\u2013 Frambons (bombones de frambuesa natural cubierto en chocolate)<\/p>\n","protected":false},"featured_media":12596,"comment_status":"open","ping_status":"closed","template":"","portfolio_entries":[104],"portfolio_tags":[],"class_list":["post-12599","dt_portfolios","type-dt_portfolios","status-publish","has-post-thumbnail","hentry","portfolio_entries-gastronomia-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guapaletas - Sunranxx<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guapaletas - Sunranxx\" \/>\n<meta property=\"og:description\" content=\"Somos una empresa dedicada a la fabricaci\u00f3n y comercializaci\u00f3n de helado artesanal en una forma distinta. Helado artesanal en palito. Llegamos a Espa\u00f1a hace m\u00e1s de un a\u00f1o y estamos presentes en varios puntos de Europa. Presentamos una forma distinta de tomar helado, con productos de fabricaci\u00f3n propia y comercializando m\u00e1s de 23 sabores 100% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunranxx\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T14:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/05\/Guapaletas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"763\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/\",\"name\":\"Guapaletas - Sunranxx\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Guapaletas.jpeg\",\"datePublished\":\"2022-05-12T13:55:29+00:00\",\"dateModified\":\"2022-05-12T14:36:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Guapaletas.jpeg\",\"contentUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Guapaletas.jpeg\",\"width\":763,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/guapaletas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/home-esp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa\",\"item\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guapaletas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/\",\"name\":\"Sunranxx\",\"description\":\"Per escapar de la monotonia i ens deixem sorprendre sensorialment.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#organization\",\"name\":\"Sunranxx\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ranxx-group.jpg\",\"contentUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ranxx-group.jpg\",\"width\":960,\"height\":960,\"caption\":\"Sunranxx\"},\"image\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guapaletas - Sunranxx","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Guapaletas - Sunranxx","og_description":"Somos una empresa dedicada a la fabricaci\u00f3n y comercializaci\u00f3n de helado artesanal en una forma distinta. Helado artesanal en palito. Llegamos a Espa\u00f1a hace m\u00e1s de un a\u00f1o y estamos presentes en varios puntos de Europa. Presentamos una forma distinta de tomar helado, con productos de fabricaci\u00f3n propia y comercializando m\u00e1s de 23 sabores 100% [&hellip;]","og_url":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/","og_site_name":"Sunranxx","article_modified_time":"2022-05-12T14:36:11+00:00","og_image":[{"width":763,"height":680,"url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/05\/Guapaletas.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/","url":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/","name":"Guapaletas - Sunranxx","isPartOf":{"@id":"https:\/\/sunranxx.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/#primaryimage"},"image":{"@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/#primaryimage"},"thumbnailUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/05\/Guapaletas.jpeg","datePublished":"2022-05-12T13:55:29+00:00","dateModified":"2022-05-12T14:36:11+00:00","breadcrumb":{"@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sunranxx.com\/es\/participant\/guapaletas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/#primaryimage","url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/05\/Guapaletas.jpeg","contentUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/05\/Guapaletas.jpeg","width":763,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/sunranxx.com\/es\/participant\/guapaletas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/sunranxx.com\/es\/home-esp\/"},{"@type":"ListItem","position":2,"name":"Participa","item":"https:\/\/sunranxx.com\/es\/participant\/"},{"@type":"ListItem","position":3,"name":"Guapaletas"}]},{"@type":"WebSite","@id":"https:\/\/sunranxx.com\/es\/#website","url":"https:\/\/sunranxx.com\/es\/","name":"Sunranxx","description":"Per escapar de la monotonia i ens deixem sorprendre sensorialment.","publisher":{"@id":"https:\/\/sunranxx.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sunranxx.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sunranxx.com\/es\/#organization","name":"Sunranxx","url":"https:\/\/sunranxx.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunranxx.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2020\/04\/ranxx-group.jpg","contentUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2020\/04\/ranxx-group.jpg","width":960,"height":960,"caption":"Sunranxx"},"image":{"@id":"https:\/\/sunranxx.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/12599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios"}],"about":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/types\/dt_portfolios"}],"replies":[{"embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/comments?post=12599"}],"version-history":[{"count":2,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/12599\/revisions"}],"predecessor-version":[{"id":12604,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/12599\/revisions\/12604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/media\/12596"}],"wp:attachment":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/media?parent=12599"}],"wp:term":[{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/portfolio_entries?post=12599"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=12599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}