{"id":13043,"date":"2022-06-04T13:04:59","date_gmt":"2022-06-04T11:04:59","guid":{"rendered":"https:\/\/sunranxx.com\/participant\/oposat\/"},"modified":"2022-06-04T13:05:44","modified_gmt":"2022-06-04T11:05:44","slug":"oposat","status":"publish","type":"dt_portfolios","link":"https:\/\/sunranxx.com\/es\/participant\/oposat\/","title":{"rendered":"Oposat"},"content":{"rendered":"<p>Opuesto es un proyecto de ropa urbana alternativa, fusi\u00f3n de dos estilos propios pero a la vez distintos.<br \/>\nSomos dos j\u00f3venes que dedicamos nuestro tiempo libre a este proyecto. Llevamos a cabo el proceso creativo y artesanal de cada prenda, y lo hacemos en un peque\u00f1o taller de confecci\u00f3n de herencia familiar en Osona.<br \/>\n100% artesanal y sostenible.<\/p>\n<p>IG: Oposat.<span class=\"hiddenSpellError\">wear<\/span><\/p>\n","protected":false},"featured_media":13040,"comment_status":"open","ping_status":"closed","template":"","portfolio_entries":[56],"portfolio_tags":[],"class_list":["post-13043","dt_portfolios","type-dt_portfolios","status-publish","has-post-thumbnail","hentry","portfolio_entries-expositores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposat - Sunranxx<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposat - Sunranxx\" \/>\n<meta property=\"og:description\" content=\"Opuesto es un proyecto de ropa urbana alternativa, fusi\u00f3n de dos estilos propios pero a la vez distintos. Somos dos j\u00f3venes que dedicamos nuestro tiempo libre a este proyecto. Llevamos a cabo el proceso creativo y artesanal de cada prenda, y lo hacemos en un peque\u00f1o taller de confecci\u00f3n de herencia familiar en Osona. 100% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sunranxx.com\/es\/participant\/oposat\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunranxx\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-04T11:05:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/06\/Oposat.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1072\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/\",\"name\":\"Oposat - Sunranxx\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oposat.jpeg\",\"datePublished\":\"2022-06-04T11:04:59+00:00\",\"dateModified\":\"2022-06-04T11:05:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oposat.jpeg\",\"contentUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oposat.jpeg\",\"width\":1072,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/oposat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/home-esp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa\",\"item\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/participant\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oposat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/\",\"name\":\"Sunranxx\",\"description\":\"Per escapar de la monotonia i ens deixem sorprendre sensorialment.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#organization\",\"name\":\"Sunranxx\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ranxx-group.jpg\",\"contentUrl\":\"https:\\\/\\\/sunranxx.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ranxx-group.jpg\",\"width\":960,\"height\":960,\"caption\":\"Sunranxx\"},\"image\":{\"@id\":\"https:\\\/\\\/sunranxx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposat - Sunranxx","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Oposat - Sunranxx","og_description":"Opuesto es un proyecto de ropa urbana alternativa, fusi\u00f3n de dos estilos propios pero a la vez distintos. Somos dos j\u00f3venes que dedicamos nuestro tiempo libre a este proyecto. Llevamos a cabo el proceso creativo y artesanal de cada prenda, y lo hacemos en un peque\u00f1o taller de confecci\u00f3n de herencia familiar en Osona. 100% [&hellip;]","og_url":"https:\/\/sunranxx.com\/es\/participant\/oposat\/","og_site_name":"Sunranxx","article_modified_time":"2022-06-04T11:05:44+00:00","og_image":[{"width":1072,"height":749,"url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/06\/Oposat.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/","url":"https:\/\/sunranxx.com\/es\/participant\/oposat\/","name":"Oposat - Sunranxx","isPartOf":{"@id":"https:\/\/sunranxx.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/#primaryimage"},"image":{"@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/#primaryimage"},"thumbnailUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/06\/Oposat.jpeg","datePublished":"2022-06-04T11:04:59+00:00","dateModified":"2022-06-04T11:05:44+00:00","breadcrumb":{"@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sunranxx.com\/es\/participant\/oposat\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/#primaryimage","url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/06\/Oposat.jpeg","contentUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2022\/06\/Oposat.jpeg","width":1072,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/sunranxx.com\/es\/participant\/oposat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/sunranxx.com\/es\/home-esp\/"},{"@type":"ListItem","position":2,"name":"Participa","item":"https:\/\/sunranxx.com\/es\/participant\/"},{"@type":"ListItem","position":3,"name":"Oposat"}]},{"@type":"WebSite","@id":"https:\/\/sunranxx.com\/es\/#website","url":"https:\/\/sunranxx.com\/es\/","name":"Sunranxx","description":"Per escapar de la monotonia i ens deixem sorprendre sensorialment.","publisher":{"@id":"https:\/\/sunranxx.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sunranxx.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sunranxx.com\/es\/#organization","name":"Sunranxx","url":"https:\/\/sunranxx.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunranxx.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sunranxx.com\/wp-content\/uploads\/2020\/04\/ranxx-group.jpg","contentUrl":"https:\/\/sunranxx.com\/wp-content\/uploads\/2020\/04\/ranxx-group.jpg","width":960,"height":960,"caption":"Sunranxx"},"image":{"@id":"https:\/\/sunranxx.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/13043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios"}],"about":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/types\/dt_portfolios"}],"replies":[{"embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/comments?post=13043"}],"version-history":[{"count":1,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/13043\/revisions"}],"predecessor-version":[{"id":13044,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/dt_portfolios\/13043\/revisions\/13044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/media\/13040"}],"wp:attachment":[{"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/media?parent=13043"}],"wp:term":[{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/portfolio_entries?post=13043"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/sunranxx.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=13043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}